{"id":579,"date":"2023-03-30T09:41:49","date_gmt":"2023-03-30T15:41:49","guid":{"rendered":"http:\/\/lenceria69.com\/cr\/?post_type=product&#038;p=579"},"modified":"2023-12-10T21:24:34","modified_gmt":"2023-12-11T03:24:34","slug":"medias-caladas-al-muslo","status":"publish","type":"product","link":"https:\/\/lenceria69.com\/cr\/producto\/medias-caladas-al-muslo\/","title":{"rendered":"Medias Caladas al Muslo"},"content":{"rendered":"<p>Un complemento que no puede hacer falta en tu conjunto sensual, muestra tus sensuales piernas a tu compa\u00f1ero de habitacion y seducelo hasta que no pueda quitarte los ojos de encima.<\/p>\n<p><strong>Material<\/strong>: Spandex con detalle de encaje<\/p>\n<p>Colores Disponibles:<br \/>\n&#8211; Blanco<br \/>\n&#8211; Negro<br \/>\n&#8211; Rojo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un complemento que no puede hacer falta en tu conjunto sensual, muestra tus sensuales piernas a tu compa\u00f1ero de habitacion y seducelo hasta que no pueda quitarte los ojos de encima. Material: Spandex con detalle de encaje Colores Disponibles: &#8211; Blanco &#8211; Negro &#8211; Rojo<\/p>\n","protected":false},"featured_media":10000059,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[]},"product_brand":[],"product_cat":[18,20],"product_tag":[],"class_list":["post-579","product","type-product","status-publish","has-post-thumbnail","product_cat-complementos","product_cat-liguerosymedias","first","instock","shipping-taxable","purchasable","product-type-variable","entry","content-bg","loop-entry"],"_links":{"self":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/579","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/comments?post=579"}],"version-history":[{"count":0,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/579\/revisions"}],"wp:attachment":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/media?parent=579"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_brand?post=579"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_cat?post=579"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_tag?post=579"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}