{"id":4118,"date":"2024-09-23T00:34:28","date_gmt":"2024-09-23T06:34:28","guid":{"rendered":"https:\/\/lenceria69.com\/cr\/?post_type=product&#038;p=4118"},"modified":"2024-09-23T00:34:48","modified_gmt":"2024-09-23T06:34:48","slug":"p69005","status":"publish","type":"product","link":"https:\/\/lenceria69.com\/cr\/producto\/p69005\/","title":{"rendered":"P69005 \u2013 Sensual Bodysuit Semistralucido"},"content":{"rendered":"<p>Aqu\u00ed tenemos el conjunto que estabas esperando para que tu pareja no te quite los ojos de encima, un bello set de Bodysuit con detalles de encaje semitraslucido que deja volar a la imaginaci\u00f3n, har\u00e1 que tu pareja solo tenga ojos para ti y para nadie m\u00e1s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed tenemos el conjunto que estabas esperando para que tu pareja no te quite los ojos de encima, un bello set de Bodysuit con detalles de encaje semitraslucido que deja volar a la imaginaci\u00f3n, har\u00e1 que tu pareja solo tenga ojos para ti y para nadie m\u00e1s.<\/p>\n","protected":false},"featured_media":4123,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[]},"product_brand":[],"product_cat":[32,37],"product_tag":[],"class_list":["post-4118","product","type-product","status-publish","has-post-thumbnail","product_cat-lenceria","product_cat-unitalla","first","instock","shipping-taxable","purchasable","product-type-variable","entry","content-bg","loop-entry"],"_links":{"self":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/4118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/comments?post=4118"}],"version-history":[{"count":1,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/4118\/revisions"}],"predecessor-version":[{"id":4140,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/4118\/revisions\/4140"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/media\/4123"}],"wp:attachment":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/media?parent=4118"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_brand?post=4118"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_cat?post=4118"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_tag?post=4118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}