{"id":1140,"date":"2023-05-26T14:16:53","date_gmt":"2023-05-26T20:16:53","guid":{"rendered":"http:\/\/lenceria69.com\/cr\/?post_type=product&#038;p=1140"},"modified":"2023-05-26T14:16:54","modified_gmt":"2023-05-26T20:16:54","slug":"shungamassage","status":"publish","type":"product","link":"https:\/\/lenceria69.com\/cr\/producto\/shungamassage\/","title":{"rendered":"Shunga Massage \u2013 Crema de Masaje Besable"},"content":{"rendered":"<p>Shunga Erotic Art Massage de exquisito gusto. Suave como la seda, comestible e hidratante. Se desliza f\u00e1cilmente y es de larga duraci\u00f3n. Deja la piel fresca y no grasosa.<br \/>\n\u00a1Esta crema dejar\u00e1 la piel con un sabor delicioso! Acaricia a tu pareja con esta deliciosa crema de masaje. Ac\u00e9rcate a tu amante con este sabroso manjar y siente la suavidad de su piel contra la tuya.<\/p>\n<p>\u00a1Deje que la tensi\u00f3n sexual suba y lleve el erotismo a su punto m\u00e1ximo!<\/p>\n<p>Sabores:<br \/>\n\u2013 Vino Espumoso de Fresa<\/p>\n<p>Volumen: tubo de 7 onzas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Shunga Erotic Art Massage de exquisito gusto. Suave como la seda, comestible e hidratante. Se desliza f\u00e1cilmente y es de larga duraci\u00f3n. Deja la piel fresca y no grasosa. \u00a1Esta crema dejar\u00e1 la piel con un sabor delicioso! Acaricia a tu pareja con esta deliciosa crema de masaje. Ac\u00e9rcate a tu amante con este sabroso&#8230;<\/p>\n","protected":false},"featured_media":100000778,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[]},"product_brand":[],"product_cat":[38,40],"product_tag":[],"class_list":["post-1140","product","type-product","status-publish","has-post-thumbnail","product_cat-lubricantes","product_cat-masajes","first","instock","shipping-taxable","purchasable","product-type-simple","entry","content-bg","loop-entry"],"_links":{"self":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/1140","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/comments?post=1140"}],"version-history":[{"count":0,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/1140\/revisions"}],"wp:attachment":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/media?parent=1140"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_brand?post=1140"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_cat?post=1140"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_tag?post=1140"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}