{"id":1095,"date":"2023-05-24T10:36:40","date_gmt":"2023-05-24T16:36:40","guid":{"rendered":"http:\/\/lenceria69.com\/cr\/?post_type=product&#038;p=1095"},"modified":"2023-05-24T10:36:40","modified_gmt":"2023-05-24T16:36:40","slug":"lhn055","status":"publish","type":"product","link":"https:\/\/lenceria69.com\/cr\/producto\/lhn055\/","title":{"rendered":"LHN055 \u2013 Sensual Conjunto De Malla"},"content":{"rendered":"<p>Aqu\u00ed tenemos el conjunto que estabas esperando para que tu pareja no te quite los ojos de encima, un bello set de malla de cuerpo completo semitraslucido que deja volar a la imaginaci\u00f3n, har\u00e1 que tu pareja solo tenga ojos para ti y para nadie m\u00e1s.<\/p>\n<p>Disponible en colores<br \/>\n\u2013 Negro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed tenemos el conjunto que estabas esperando para que tu pareja no te quite los ojos de encima, un bello set de malla de cuerpo completo semitraslucido que deja volar a la imaginaci\u00f3n, har\u00e1 que tu pareja solo tenga ojos para ti y para nadie m\u00e1s. Disponible en colores \u2013 Negro<\/p>\n","protected":false},"featured_media":1000001046,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","_joinchat":[]},"product_brand":[],"product_cat":[32,37],"product_tag":[],"class_list":["post-1095","product","type-product","status-publish","has-post-thumbnail","product_cat-lenceria","product_cat-unitalla","first","instock","shipping-taxable","purchasable","product-type-simple","entry","content-bg","loop-entry"],"_links":{"self":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/1095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/comments?post=1095"}],"version-history":[{"count":0,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product\/1095\/revisions"}],"wp:attachment":[{"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/media?parent=1095"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_brand?post=1095"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_cat?post=1095"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lenceria69.com\/cr\/wp-json\/wp\/v2\/product_tag?post=1095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}